{"id":26166,"date":"2026-03-20T12:27:58","date_gmt":"2026-03-20T12:27:58","guid":{"rendered":"https:\/\/sodepal.es\/?p=26166"},"modified":"2026-03-20T12:30:31","modified_gmt":"2026-03-20T12:30:31","slug":"renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid","status":"publish","type":"post","link":"https:\/\/sodepal.es\/en\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\/","title":{"rendered":"RENACER: la joyer\u00eda de autor de La Palma celebra la resiliencia y la transformaci\u00f3n durante la Semana de La Moda de Madrid"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"26166\" class=\"elementor elementor-26166\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-36d1fa0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"36d1fa0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-20481759\" data-id=\"20481759\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-203ce316 elementor-widget elementor-widget-text-editor\" data-id=\"203ce316\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"field field--name-field-noticias-entradilla field--type-text-long field--label-hidden field--item\"><div class=\"field field--name-field-noticias-entradilla field--type-text-long field--label-hidden field--item\"><div class=\"field field--name-field-noticias-entradilla field--type-text-long field--label-hidden field--item\"><div class=\"field field--name-field-noticias-entradilla field--type-text-long field--label-hidden field--item\"><div class=\"field field--name-field-noticias-entradilla field--type-text-long field--label-hidden field--item\"><div class=\"field field--name-field-noticias-entradilla field--type-text-long field--label-hidden field--item\"><div class=\"field field--name-field-noticias-entradilla field--type-text-long field--label-hidden field--item\"><div class=\"field field--name-field-noticias-entradilla field--type-text-long field--label-hidden field--item\"><p>El programa insular\u00a0Isla Bonita Moda, impulsado por el Cabildo Insular de La Palma a trav\u00e9s de\u00a0Sodepal, present\u00f3\u00a0Renacer, un encuentro dedicado a la joyer\u00eda de autor que se celebr\u00f3 en el marco oficial de\u00a0OMODA Madrid es Moda, dentro de la programaci\u00f3n de la\u00a0Semana de la Moda de Madrid.<\/p><p>La iniciativa se organiz\u00f3 en colaboraci\u00f3n con la Asociaci\u00f3n Creadores de Moda de Espa\u00f1a (ACME), de la que Isla Bonita Moda es instituci\u00f3n asociada, dentro de su programa de impulso a la moda en La Palma. En esta ocasi\u00f3n, la propuesta se centra en poner en valor el talento creativo y artesanal de las firmas de joyer\u00eda vinculadas al sello.<\/p><p>Renacer\u00a0rindi\u00f3 homenaje al poder transformador de la naturaleza y al talento creativo de los dise\u00f1adores asociados mediante un proyecto que establece un paralelismo entre el\u00a0proceso alqu\u00edmico de la joyer\u00eda\u00a0\u2014en el que los materiales se transforman mediante el fuego, la t\u00e9cnica y el tiempo hasta convertirse en piezas de belleza\u2014 y el\u00a0proceso alqu\u00edmico de la propia isla de La Palma, marcada por la fuerza volc\u00e1nica que moldea su paisaje y su identidad.<\/p><p>Inspiradas en esta conexi\u00f3n, las piezas exploraron la fuerza del fuego volc\u00e1nico, la solidez de la lava, la transparencia del cristal y la magia de la transformaci\u00f3n. Fue un viaje simb\u00f3lico desde la destrucci\u00f3n hasta la resiliencia, el renacimiento y la fertilidad, donde cada joya se convirti\u00f3 en un testimonio de c\u00f3mo la materia puede transformarse en belleza y significado.<\/p><p>El evento se celebr\u00f3 en la casa del reconocido dise\u00f1ador de interiores\u00a0Tom\u00e1s Al\u00eda, uno de los grandes referentes del dise\u00f1o espa\u00f1ol contempor\u00e1neo, maestro de la artesan\u00eda y galardonado con la\u00a0Medalla de Oro al M\u00e9rito en las Bellas Artes\u00a0en 2022. Su hogar se convirti\u00f3 en el escenario de esta experiencia creativa, aportando un marco \u00fanico y sofisticado que conect\u00f3 con valores compartidos como la familia, el hogar, el cuidado por el detalle, la creatividad singular y el respeto por la tradici\u00f3n y el patrimonio.<\/p><p>La muestra expositiva reuni\u00f3 a siete firmas de joyer\u00eda de autor asociadas al colectivo, que reinterpretaron el concepto de\u00a0Renacer\u00a0desde su propia mirada art\u00edstica:<\/p><p>Atelier El Tesoro, con su creadora\u00a0Anna Joos,\u00a0present\u00f3 un collar que rindi\u00f3 homenaje a la fuerza indomable de La Palma. La pieza recre\u00f3, mediante cer\u00e1mica de alta calidad quemada en alta temperatura, la textura porosa y org\u00e1nica de la lava volc\u00e1nica, simbolizando el paso de la oscuridad del magma a la fertilidad del nuevo suelo. Fue una pieza de arte port\u00e1til que celebr\u00f3 la resiliencia y el ciclo eterno de transformaci\u00f3n, cristalizaci\u00f3n y vida.<\/p><p>Ferreiro\u00a0present\u00f3 la colecci\u00f3n\u00a0Tetraedros, inspirada en la estructura molecular del basalto que surge al solidificarse la lava volc\u00e1nica. Para\u00a0Pedro Ferreiro,\u00a0sus piezas combinaron estructuras geom\u00e9tricas detetraedros enlazados con cuentas de lava volc\u00e1nica, estableciendo un di\u00e1logo entre el caos de la erupci\u00f3n y el orden natural que subyace en la materia.<\/p><p>\u00a0<\/p><p>Lepa Punca, fundada por\u00a0Melisa Rodr\u00edguez,\u00a0present\u00f3 piezas inspiradas en el proceso de cristalizaci\u00f3n de los minerales: un proceso m\u00e1gico en el que luces y sombras dieron lugar a estructuras verticales y oblicuas que evocaron un renacer conceptual. En estas creaciones, la plata y la piedra luna actuaron como elementos protagonistas que canalizaron la forma y la luz del proceso de transformaci\u00f3n.<\/p><p>Alejandro Marante, fundador de\u00a0Mararte,\u00a0se inspir\u00f3 en las ac\u00edculas del pino canario \u2014 s\u00edmbolo de fuerza y resistencia\u2014 y en la textura de la piedra volc\u00e1nica, incorporando ceniza volc\u00e1nica del volc\u00e1n Tajogaite en sus creaciones.<\/p><p>Ra\u00fal Vargas\u00a0present\u00f3 una pieza protagonizada por una lib\u00e9lula de plata que surgi\u00f3 del paisaje posterior a la erupci\u00f3n: el instante en el que el fuego hab\u00eda pasado y la tierra comenzaba a prepararse para un nuevo comienzo. Trabajada en filigrana, la pieza combin\u00f3 granates \u2014s\u00edmbolo del fuego transformador\u2014 con flores de olivina y un \u00f3palo central que introdujo el elemento agua, evocando el ciclo completo de transformaci\u00f3n de la naturaleza.<\/p><p>Sara Luis, de\u00a0Sara Luis Joyas,\u00a0present\u00f3 Gloriosa Superba, una colecci\u00f3n inspirada en el lirio de fuego, una flor que simboliza el renacer. Al finalizar su ciclo, su parte visible desaparece, pero su ra\u00edz permanece viva bajo la tierra y vuelve a brotar en la temporada siguiente. Realizadas en lat\u00f3n y esmalte, las piezas capturan el movimiento natural de la flor con curvas ascendentes y p\u00e9talos que evocan llamas. La colecci\u00f3n representa la fuerza interior que permanece incluso en los momentos m\u00e1s dif\u00edciles y la capacidad de transformarse, levantarse y renacer.<\/p><p>Silvia Baly\u00a0present\u00f3 una colecci\u00f3n que naci\u00f3 del silencio despu\u00e9s del Inspiradas en el proceso volc\u00e1nico de La Palma, sus piezas estaban elaboradas en plata lisa tejida a mano como si fuera hilo, generando estructuras org\u00e1nicas y flexibles que se adaptaron al cuerpo. La presencia de piedras verdes simboliz\u00f3 la vida que volvi\u00f3 a brotar sobre la tierra transformada.<\/p><p>A trav\u00e9s de todas estas propuestas,\u00a0Renacer\u00a0ofreci\u00f3 una experiencia en la que arte, joyer\u00eda y dise\u00f1o convergieron para contar una historia com\u00fan: la de la transformaci\u00f3n de la materia, del territorio y de la creatividad.<\/p><p>Miriam Perestelo Rodr\u00edguez, consejera de Promoci\u00f3n Econ\u00f3mica del Cabildo Insular de La Palma y consejera delegada de Sodepal, destac\u00f3 la importancia de esta iniciativa para el sector creativo en el \u00e1mbito de la moda de la isla: \u201cdesde el Cabildo de La Palma nos sentimos profundamente orgullosos del talento de nuestro colectivo de joyeros. Se trata de un sector muy especializado que ha sabido profesionalizarse y proyectar su trabajo m\u00e1s all\u00e1 de la isla, mostrando el enorme valor de la artesan\u00eda contempor\u00e1nea que aqu\u00ed se desarrolla. La participaci\u00f3n en Madrid es Moda,dentro de la Semana de la Moda de Madrid y en colaboraci\u00f3n con ACME, permiti\u00f3 situar este talento en un contexto de gran visibilidad nacional, conect\u00e1ndolo con el ecosistema creativo del dise\u00f1o y la moda en Espa\u00f1a. Renacer simboliz\u00f3 adem\u00e1s la capacidad de transformaci\u00f3n de nuestra isla y de nuestra gente. Celebrarlo en la casa de Tom\u00e1s Al\u00eda, una figura fundamental del dise\u00f1o espa\u00f1ol y un gran defensor de la artesan\u00eda, reforz\u00f3 ese di\u00e1logo entre tradici\u00f3n, creatividad y patrimonio cultural que define el esp\u00edritu de Isla Bonita Moda\u201d.<\/p><p>Con\u00a0Renacer, Isla Bonita Moda contin\u00faa impulsando la proyecci\u00f3n del talento creativo palmero, consolidando la presencia de la isla en uno de los escenarios m\u00e1s relevantes para el dise\u00f1o y la moda en Espa\u00f1a.<\/p><p>ABOUT THE SPANISH FASHION DESIGNERS ASSOCIATION (ACME)<\/p><p>La Asociaci\u00f3n Creadores de Moda de Espa\u00f1a (ACME) es una asociaci\u00f3n profesional sin \u00e1nimo de lucro que actualmente est\u00e1 formada por 96 creadores de moda de toda la geograf\u00eda espa\u00f1ola que participan en las principales pasarelas y plataformas de moda tanto a nivel nacional como internacional, 4 instituciones asociadas y Amazon Fashion como Benefactor.<\/p><p>Founded in 1998 by designers Modesto Lomba, Jes\u00fas del Pozo, Elio Berhanyer, Antonio Pernas, \u00c1ngel Fern\u00e1ndez Ovejero (Angel Schlesser) and Roberto Verino, since its inception, the Asociaci\u00f3n Creadores de Moda de Espa\u00f1a has worked to defend the interests of designer fashion firms, offering tools to increase their competitiveness.<\/p><p>ACME aims to promote Spanish fashion in its economic and cultural facets, encouraging activities that benefit the fashion design sector in its creative and commercial aspects, both inside and outside Spain.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>El programa insular\u00a0Isla Bonita Moda, impulsado por el Cabildo Insular de La Palma a trav\u00e9s de\u00a0Sodepal, present\u00f3\u00a0Renacer, un encuentro dedicado a la joyer\u00eda de autor que se celebr\u00f3 en el marco oficial de\u00a0OMODA Madrid es Moda, dentro de la programaci\u00f3n de la\u00a0Semana de la Moda de Madrid. La iniciativa se organiz\u00f3 en colaboraci\u00f3n con la &#8230; <a title=\"RENACER: la joyer\u00eda de autor de La Palma celebra la resiliencia y la transformaci\u00f3n durante la Semana de La Moda de Madrid\" class=\"read-more\" href=\"https:\/\/sodepal.es\/en\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\/\" aria-label=\"Read more about RENACER: la joyer\u00eda de autor de La Palma celebra la resiliencia y la transformaci\u00f3n durante la Semana de La Moda de Madrid\">Read more<\/a><\/p>","protected":false},"author":1,"featured_media":26169,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-26166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.0 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>RENACER: la joyer\u00eda de autor de La Palma celebra la resiliencia y la transformaci\u00f3n durante la Semana de La Moda de Madrid - Sociedad de Promoci\u00f3n y Desarrollo Econ\u00f3mico y Social de La Palma - SODEPAL<\/title>\n<meta name=\"description\" content=\"Toda la actualidad de los proyectos y eventos desarrollados por SODEPAL\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sodepal.es\/en\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RENACER: la joyer\u00eda de autor de La Palma celebra la resiliencia y la transformaci\u00f3n durante la Semana de La Moda de Madrid\" \/>\n<meta property=\"og:description\" content=\"Toda la actualidad de los proyectos y eventos desarrollados por SODEPAL\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sodepal.es\/en\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\/\" \/>\n<meta property=\"og:site_name\" content=\"Sociedad de Promoci\u00f3n y Desarrollo Econ\u00f3mico y Social de La Palma - SODEPAL\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sodepal\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-20T12:27:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-20T12:30:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sodepal.es\/wp-content\/uploads\/2026\/03\/NP_Renacer.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gerencia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sodepal.es\\\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sodepal.es\\\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\\\/\"},\"author\":{\"name\":\"gerencia\",\"@id\":\"https:\\\/\\\/sodepal.es\\\/#\\\/schema\\\/person\\\/43b1d623bde0c4ec4efd5656ef0958b2\"},\"headline\":\"RENACER: la joyer\u00eda de autor de La Palma celebra la resiliencia y la transformaci\u00f3n durante la Semana de La Moda de Madrid\",\"datePublished\":\"2026-03-20T12:27:58+00:00\",\"dateModified\":\"2026-03-20T12:30:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sodepal.es\\\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\\\/\"},\"wordCount\":1345,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/sodepal.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sodepal.es\\\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sodepal.es\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/NP_Renacer.jpeg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sodepal.es\\\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sodepal.es\\\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\\\/\",\"url\":\"https:\\\/\\\/sodepal.es\\\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\\\/\",\"name\":\"RENACER: la joyer\u00eda de autor de La Palma celebra la resiliencia y la transformaci\u00f3n durante la Semana de La Moda de Madrid - Sociedad de Promoci\u00f3n y Desarrollo Econ\u00f3mico y Social de La Palma - SODEPAL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sodepal.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sodepal.es\\\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sodepal.es\\\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sodepal.es\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/NP_Renacer.jpeg\",\"datePublished\":\"2026-03-20T12:27:58+00:00\",\"dateModified\":\"2026-03-20T12:30:31+00:00\",\"description\":\"Toda la actualidad de los proyectos y eventos desarrollados por SODEPAL\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sodepal.es\\\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sodepal.es\\\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/sodepal.es\\\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sodepal.es\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/NP_Renacer.jpeg\",\"contentUrl\":\"https:\\\/\\\/sodepal.es\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/NP_Renacer.jpeg\",\"width\":2560,\"height\":1708},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sodepal.es\\\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sodepal.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RENACER: la joyer\u00eda de autor de La Palma celebra la resiliencia y la transformaci\u00f3n durante la Semana de La Moda de Madrid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sodepal.es\\\/#website\",\"url\":\"https:\\\/\\\/sodepal.es\\\/\",\"name\":\"Sodepal\",\"description\":\"SODEPAL es una empresa p\u00fablica dependiente del Cabildo de La Palma. Promoci\u00f3n, Fomento y Desarrollo para la isla de La Palma\",\"publisher\":{\"@id\":\"https:\\\/\\\/sodepal.es\\\/#organization\"},\"alternateName\":\"Sociedad de Promoci\u00f3n y Desarrollo Econ\u00f3mico y Social de La Palma\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sodepal.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sodepal.es\\\/#organization\",\"name\":\"Sociedad de Promoci\u00f3n y Desarrollo Econ\u00f3mico y Social de La Palma\",\"alternateName\":\"Sodepal\",\"url\":\"https:\\\/\\\/sodepal.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/sodepal.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sodepal.es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/logo_web.png\",\"contentUrl\":\"https:\\\/\\\/sodepal.es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/logo_web.png\",\"width\":658,\"height\":156,\"caption\":\"Sociedad de Promoci\u00f3n y Desarrollo Econ\u00f3mico y Social de La Palma\"},\"image\":{\"@id\":\"https:\\\/\\\/sodepal.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sodepal\",\"https:\\\/\\\/www.instagram.com\\\/sodepallapalma\\\/\"],\"description\":\"Sociedad de Promoci\u00f3n y Desarrollo econ\u00f3mico y Social de La Palma, empresa p\u00fablica dependiente del Cabildo de La Palma\",\"email\":\"info@sodepal.es\",\"telephone\":\"922417323\",\"legalName\":\"Sociedad de Promoci\u00f3n y Desarrollo Econ\u00f3mico de la isla de La Palma S.A.U.\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sodepal.es\\\/#\\\/schema\\\/person\\\/43b1d623bde0c4ec4efd5656ef0958b2\",\"name\":\"gerencia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2aa1ba3e33e6721e413a7499ea7cab2e4414b99cea1516e7404245c8da655d86?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2aa1ba3e33e6721e413a7499ea7cab2e4414b99cea1516e7404245c8da655d86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2aa1ba3e33e6721e413a7499ea7cab2e4414b99cea1516e7404245c8da655d86?s=96&d=mm&r=g\",\"caption\":\"gerencia\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"RENACER: la joyer\u00eda de autor de La Palma celebra la resiliencia y la transformaci\u00f3n durante la Semana de La Moda de Madrid - Sociedad de Promoci\u00f3n y Desarrollo Econ\u00f3mico y Social de La Palma - SODEPAL","description":"Toda la actualidad de los proyectos y eventos desarrollados por SODEPAL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sodepal.es\/en\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\/","og_locale":"en_GB","og_type":"article","og_title":"RENACER: la joyer\u00eda de autor de La Palma celebra la resiliencia y la transformaci\u00f3n durante la Semana de La Moda de Madrid","og_description":"Toda la actualidad de los proyectos y eventos desarrollados por SODEPAL","og_url":"https:\/\/sodepal.es\/en\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\/","og_site_name":"Sociedad de Promoci\u00f3n y Desarrollo Econ\u00f3mico y Social de La Palma - SODEPAL","article_publisher":"https:\/\/www.facebook.com\/sodepal","article_published_time":"2026-03-20T12:27:58+00:00","article_modified_time":"2026-03-20T12:30:31+00:00","og_image":[{"width":2560,"height":1708,"url":"https:\/\/sodepal.es\/wp-content\/uploads\/2026\/03\/NP_Renacer.jpeg","type":"image\/jpeg"}],"author":"gerencia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sodepal.es\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\/#article","isPartOf":{"@id":"https:\/\/sodepal.es\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\/"},"author":{"name":"gerencia","@id":"https:\/\/sodepal.es\/#\/schema\/person\/43b1d623bde0c4ec4efd5656ef0958b2"},"headline":"RENACER: la joyer\u00eda de autor de La Palma celebra la resiliencia y la transformaci\u00f3n durante la Semana de La Moda de Madrid","datePublished":"2026-03-20T12:27:58+00:00","dateModified":"2026-03-20T12:30:31+00:00","mainEntityOfPage":{"@id":"https:\/\/sodepal.es\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\/"},"wordCount":1345,"commentCount":0,"publisher":{"@id":"https:\/\/sodepal.es\/#organization"},"image":{"@id":"https:\/\/sodepal.es\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/sodepal.es\/wp-content\/uploads\/2026\/03\/NP_Renacer.jpeg","articleSection":["Noticias"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sodepal.es\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sodepal.es\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\/","url":"https:\/\/sodepal.es\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\/","name":"RENACER: la joyer\u00eda de autor de La Palma celebra la resiliencia y la transformaci\u00f3n durante la Semana de La Moda de Madrid - Sociedad de Promoci\u00f3n y Desarrollo Econ\u00f3mico y Social de La Palma - SODEPAL","isPartOf":{"@id":"https:\/\/sodepal.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sodepal.es\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\/#primaryimage"},"image":{"@id":"https:\/\/sodepal.es\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/sodepal.es\/wp-content\/uploads\/2026\/03\/NP_Renacer.jpeg","datePublished":"2026-03-20T12:27:58+00:00","dateModified":"2026-03-20T12:30:31+00:00","description":"Toda la actualidad de los proyectos y eventos desarrollados por SODEPAL","breadcrumb":{"@id":"https:\/\/sodepal.es\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sodepal.es\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/sodepal.es\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\/#primaryimage","url":"https:\/\/sodepal.es\/wp-content\/uploads\/2026\/03\/NP_Renacer.jpeg","contentUrl":"https:\/\/sodepal.es\/wp-content\/uploads\/2026\/03\/NP_Renacer.jpeg","width":2560,"height":1708},{"@type":"BreadcrumbList","@id":"https:\/\/sodepal.es\/renacer-la-joyeria-de-autor-de-la-palma-celebra-la-resiliencia-y-la-transformacion-durante-la-semana-de-la-moda-de-madrid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sodepal.es\/"},{"@type":"ListItem","position":2,"name":"RENACER: la joyer\u00eda de autor de La Palma celebra la resiliencia y la transformaci\u00f3n durante la Semana de La Moda de Madrid"}]},{"@type":"WebSite","@id":"https:\/\/sodepal.es\/#website","url":"https:\/\/sodepal.es\/","name":"Sodepal","description":"SODEPAL es una empresa p\u00fablica dependiente del Cabildo de La Palma. Promoci\u00f3n, Fomento y Desarrollo para la isla de La Palma","publisher":{"@id":"https:\/\/sodepal.es\/#organization"},"alternateName":"Sociedad de Promoci\u00f3n y Desarrollo Econ\u00f3mico y Social de La Palma","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sodepal.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/sodepal.es\/#organization","name":"Sociedad de Promoci\u00f3n y Desarrollo Econ\u00f3mico y Social de La Palma","alternateName":"Sodepal","url":"https:\/\/sodepal.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/sodepal.es\/#\/schema\/logo\/image\/","url":"https:\/\/sodepal.es\/wp-content\/uploads\/2022\/09\/logo_web.png","contentUrl":"https:\/\/sodepal.es\/wp-content\/uploads\/2022\/09\/logo_web.png","width":658,"height":156,"caption":"Sociedad de Promoci\u00f3n y Desarrollo Econ\u00f3mico y Social de La Palma"},"image":{"@id":"https:\/\/sodepal.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sodepal","https:\/\/www.instagram.com\/sodepallapalma\/"],"description":"Sociedad de Promoci\u00f3n y Desarrollo econ\u00f3mico y Social de La Palma, empresa p\u00fablica dependiente del Cabildo de La Palma","email":"info@sodepal.es","telephone":"922417323","legalName":"Sociedad de Promoci\u00f3n y Desarrollo Econ\u00f3mico de la isla de La Palma S.A.U."},{"@type":"Person","@id":"https:\/\/sodepal.es\/#\/schema\/person\/43b1d623bde0c4ec4efd5656ef0958b2","name":"gerencia","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2aa1ba3e33e6721e413a7499ea7cab2e4414b99cea1516e7404245c8da655d86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2aa1ba3e33e6721e413a7499ea7cab2e4414b99cea1516e7404245c8da655d86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2aa1ba3e33e6721e413a7499ea7cab2e4414b99cea1516e7404245c8da655d86?s=96&d=mm&r=g","caption":"gerencia"}}]}},"_links":{"self":[{"href":"https:\/\/sodepal.es\/en\/wp-json\/wp\/v2\/posts\/26166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sodepal.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sodepal.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sodepal.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sodepal.es\/en\/wp-json\/wp\/v2\/comments?post=26166"}],"version-history":[{"count":7,"href":"https:\/\/sodepal.es\/en\/wp-json\/wp\/v2\/posts\/26166\/revisions"}],"predecessor-version":[{"id":26175,"href":"https:\/\/sodepal.es\/en\/wp-json\/wp\/v2\/posts\/26166\/revisions\/26175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sodepal.es\/en\/wp-json\/wp\/v2\/media\/26169"}],"wp:attachment":[{"href":"https:\/\/sodepal.es\/en\/wp-json\/wp\/v2\/media?parent=26166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sodepal.es\/en\/wp-json\/wp\/v2\/categories?post=26166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sodepal.es\/en\/wp-json\/wp\/v2\/tags?post=26166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}